﻿{"id":1231,"date":"2015-05-26T12:47:00","date_gmt":"2015-05-26T11:47:00","guid":{"rendered":"http:\/\/www.orionpx.fr\/project\/blog\/?p=1231"},"modified":"2015-05-26T12:47:00","modified_gmt":"2015-05-26T11:47:00","slug":"la-nebuleuse-du-papillon","status":"publish","type":"post","link":"https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/","title":{"rendered":"La n\u00e9buleuse du Papillon"},"content":{"rendered":"<p><a href=\"http:\/\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/05\/ngc-6302.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1230\" data-permalink=\"https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/ngc-6302\/\" data-orig-file=\"https:\/\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/05\/ngc-6302.jpg\" data-orig-size=\"3017,3601\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"ngc-6302\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/05\/ngc-6302-858x1024.jpg\" class=\"alignleft size-medium wp-image-1230\" src=\"http:\/\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/05\/ngc-6302-251x300.jpg\" alt=\"ngc-6302\" width=\"251\" height=\"300\" srcset=\"https:\/\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/05\/ngc-6302-251x300.jpg 251w, https:\/\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/05\/ngc-6302-858x1024.jpg 858w\" sizes=\"auto, (max-width: 251px) 100vw, 251px\" \/><\/a>Cette magnifique photographie a \u00e9t\u00e9 prise par le t\u00e9lescope spatial Hubble en novembre 2011. Il s&rsquo;agit de la n\u00e9buleuse plan\u00e9taire du Papillon (ou <a href=\"http:\/\/apod.nasa.gov\/apod\/ap111113.html\" target=\"_blank\">NGC 6302<\/a>), visible dans la constellation du Scorpion et distante de 4000 ann\u00e9es lumi\u00e8res de la Terre. Une n\u00e9buleuse plan\u00e9taire n&rsquo;a, en r\u00e9alit\u00e9, aucun rapport avec les plan\u00e8tes. C&rsquo;est l&rsquo;aspect circulaire de la plupart d\u2019entre-elles qui faisait penser les astronomes du 18\u00e8me si\u00e8cle \u00e0 la\u00a0 forme d&rsquo;une plan\u00e8te.<\/p>\n<p>L&rsquo;\u00e9toile qui est responsable de ce spectacle incroyable, approche de la <a href=\"http:\/\/www.orionpx.fr\/project\/blog\/les-etoiles-qui-sont-elles\/\" target=\"_blank\">fin du stade de g\u00e9ante rouge et va devenir une naine blanche<\/a>. Elle est donc en train de mourir et expulse ses couches externes vers l&rsquo;espace.<\/p>\n<p><a href=\"http:\/\/adsabs.harvard.edu\/abs\/2009ApJ...707L..32S\" target=\"_blank\">D\u00e9couverte seulement en 2009<\/a> (alors que la n\u00e9buleuse est connue depuis 1888), l&rsquo;\u00e9toile rayonne activement dans l&rsquo;ultraviolet et ne peut \u00eatre distingu\u00e9e sur cette photo en raison du tore de poussi\u00e8re qui l&rsquo;entoure et qui provoque cette g\u00e9om\u00e9trie particuli\u00e8re aux gaz expuls\u00e9s. Sa temp\u00e9rature de surface est de plus de 250 000\u00b0C, ce qui en fait l&rsquo;une des plus chaude jamais recens\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette magnifique photographie a \u00e9t\u00e9 prise par le t\u00e9lescope spatial Hubble en novembre 2011. Il s&rsquo;agit de la n\u00e9buleuse plan\u00e9taire du Papillon (ou NGC 6302), visible dans la constellation du Scorpion et distante de 4000 ann\u00e9es lumi\u00e8res de la Terre. Une n\u00e9buleuse plan\u00e9taire n&rsquo;a, en r\u00e9alit\u00e9, aucun rapport avec les plan\u00e8tes. C&rsquo;est l&rsquo;aspect circulaire de &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":8,"featured_media":1230,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[60],"tags":[72,142,143,88,144,141],"class_list":["post-1231","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-la-photo-qui-sort-du-lot","tag-etoile","tag-geante-rouge","tag-naine-blanche","tag-nebuleuse","tag-ngc6302","tag-papillon","post_format-post-format-image","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La n\u00e9buleuse du Papillon - Orion PX<\/title>\n<meta name=\"description\" content=\"Il s&#039;agit de la n\u00e9buleuse plan\u00e9taire du Papillon (ou NGC 6302). Visible dans la constellation du Scorpion. Une n\u00e9buleuse plan\u00e9taire n&#039;a, en r\u00e9alit\u00e9, aucun rapport avec les plan\u00e8tes. C&#039;est l&#039;aspect circulaire de la plupart d\u2019entre-elles qui faisait penser aux plan\u00e8tes pour les astronomes du 18\u00e8me si\u00e8cle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La n\u00e9buleuse du Papillon - Orion PX\" \/>\n<meta property=\"og:description\" content=\"Il s&#039;agit de la n\u00e9buleuse plan\u00e9taire du Papillon (ou NGC 6302). Visible dans la constellation du Scorpion. Une n\u00e9buleuse plan\u00e9taire n&#039;a, en r\u00e9alit\u00e9, aucun rapport avec les plan\u00e8tes. C&#039;est l&#039;aspect circulaire de la plupart d\u2019entre-elles qui faisait penser aux plan\u00e8tes pour les astronomes du 18\u00e8me si\u00e8cle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/\" \/>\n<meta property=\"og:site_name\" content=\"Orion PX\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-26T11:47:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/05\/ngc-6302-858x1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"858\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"C.P. Rigel\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"C.P. Rigel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/la-nebuleuse-du-papillon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/la-nebuleuse-du-papillon\\\/\"},\"author\":{\"name\":\"C.P. Rigel\",\"@id\":\"http:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/#\\\/schema\\\/person\\\/07536b10706cdf8a2a70fbd17f50de23\"},\"headline\":\"La n\u00e9buleuse du Papillon\",\"datePublished\":\"2015-05-26T11:47:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/la-nebuleuse-du-papillon\\\/\"},\"wordCount\":193,\"commentCount\":0,\"publisher\":{\"@id\":\"http:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/#\\\/schema\\\/person\\\/07536b10706cdf8a2a70fbd17f50de23\"},\"image\":{\"@id\":\"https:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/la-nebuleuse-du-papillon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/ngc-6302.jpg\",\"keywords\":[\"\u00e9toile\",\"g\u00e9ante rouge\",\"naine blanche\",\"n\u00e9buleuse\",\"NGC6302\",\"papillon\"],\"articleSection\":[\"La photo qui sort du lot\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/la-nebuleuse-du-papillon\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/la-nebuleuse-du-papillon\\\/\",\"url\":\"https:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/la-nebuleuse-du-papillon\\\/\",\"name\":\"La n\u00e9buleuse du Papillon - Orion PX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/la-nebuleuse-du-papillon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/la-nebuleuse-du-papillon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/ngc-6302.jpg\",\"datePublished\":\"2015-05-26T11:47:00+00:00\",\"description\":\"Il s'agit de la n\u00e9buleuse plan\u00e9taire du Papillon (ou NGC 6302). Visible dans la constellation du Scorpion. Une n\u00e9buleuse plan\u00e9taire n'a, en r\u00e9alit\u00e9, aucun rapport avec les plan\u00e8tes. C'est l'aspect circulaire de la plupart d\u2019entre-elles qui faisait penser aux plan\u00e8tes pour les astronomes du 18\u00e8me si\u00e8cle.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/la-nebuleuse-du-papillon\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/la-nebuleuse-du-papillon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/la-nebuleuse-du-papillon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/ngc-6302.jpg\",\"contentUrl\":\"https:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/ngc-6302.jpg\",\"width\":3017,\"height\":3601},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/la-nebuleuse-du-papillon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La n\u00e9buleuse du Papillon\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/#website\",\"url\":\"http:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/\",\"name\":\"Orion PX\",\"description\":\"Blog de C.P. Rigel - Auteur de Science-Fiction\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/#\\\/schema\\\/person\\\/07536b10706cdf8a2a70fbd17f50de23\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/#\\\/schema\\\/person\\\/07536b10706cdf8a2a70fbd17f50de23\",\"name\":\"C.P. Rigel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e4068dd5805dde1b4f1eca56e9247172d1266f72247697e59e0bd6ba6d631551?s=96&d=identicon&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e4068dd5805dde1b4f1eca56e9247172d1266f72247697e59e0bd6ba6d631551?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e4068dd5805dde1b4f1eca56e9247172d1266f72247697e59e0bd6ba6d631551?s=96&d=identicon&r=g\",\"caption\":\"C.P. Rigel\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e4068dd5805dde1b4f1eca56e9247172d1266f72247697e59e0bd6ba6d631551?s=96&d=identicon&r=g\"},\"description\":\"Je suis C.P. Rigel, analyste technique en informatique, je d\u00e9veloppe des logiciels pour une banque nord-am\u00e9ricaine. N\u00e9 en 1980, papa de deux formidables enfants, j\u2019ai la chance d\u2019avoir une vie de famille heureuse et bien remplie en France dans le d\u00e9partement de la Moselle. Curieux de tout, car pour moi tout est curieux. J\u2019ai ce besoin visc\u00e9ral d\u2019observer, d\u00e9cortiquer, d\u00e9monter, comprendre et apprendre. Tout est source de d\u00e9couverte et d\u2019\u00e9merveillement. Il \u00e9tait donc logique qu\u2019un jour je me tourne vers les myst\u00e8res de l\u2019univers. F\u00e9ru d\u2019astrophysique, de physique, et d\u2019astronomie, je n\u2019en suis pas moins un parfait amateur. J\u2019aime apprendre par moi-m\u00eame et d\u00e9battre de mes acquis pour les mettre \u00e0 l\u2019\u00e9preuve. (Le reste de ma biographie ici)\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/Cprigel\"],\"url\":\"https:\\\/\\\/www.orionpx.fr\\\/project\\\/blog\\\/author\\\/cprigel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La n\u00e9buleuse du Papillon - Orion PX","description":"Il s'agit de la n\u00e9buleuse plan\u00e9taire du Papillon (ou NGC 6302). Visible dans la constellation du Scorpion. Une n\u00e9buleuse plan\u00e9taire n'a, en r\u00e9alit\u00e9, aucun rapport avec les plan\u00e8tes. C'est l'aspect circulaire de la plupart d\u2019entre-elles qui faisait penser aux plan\u00e8tes pour les astronomes du 18\u00e8me si\u00e8cle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/","og_locale":"fr_FR","og_type":"article","og_title":"La n\u00e9buleuse du Papillon - Orion PX","og_description":"Il s'agit de la n\u00e9buleuse plan\u00e9taire du Papillon (ou NGC 6302). Visible dans la constellation du Scorpion. Une n\u00e9buleuse plan\u00e9taire n'a, en r\u00e9alit\u00e9, aucun rapport avec les plan\u00e8tes. C'est l'aspect circulaire de la plupart d\u2019entre-elles qui faisait penser aux plan\u00e8tes pour les astronomes du 18\u00e8me si\u00e8cle.","og_url":"https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/","og_site_name":"Orion PX","article_published_time":"2015-05-26T11:47:00+00:00","og_image":[{"width":858,"height":1024,"url":"https:\/\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/05\/ngc-6302-858x1024.jpg","type":"image\/jpeg"}],"author":"C.P. Rigel","twitter_misc":{"\u00c9crit par":"C.P. Rigel","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/#article","isPartOf":{"@id":"https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/"},"author":{"name":"C.P. Rigel","@id":"http:\/\/www.orionpx.fr\/project\/blog\/#\/schema\/person\/07536b10706cdf8a2a70fbd17f50de23"},"headline":"La n\u00e9buleuse du Papillon","datePublished":"2015-05-26T11:47:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/"},"wordCount":193,"commentCount":0,"publisher":{"@id":"http:\/\/www.orionpx.fr\/project\/blog\/#\/schema\/person\/07536b10706cdf8a2a70fbd17f50de23"},"image":{"@id":"https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/05\/ngc-6302.jpg","keywords":["\u00e9toile","g\u00e9ante rouge","naine blanche","n\u00e9buleuse","NGC6302","papillon"],"articleSection":["La photo qui sort du lot"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/","url":"https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/","name":"La n\u00e9buleuse du Papillon - Orion PX","isPartOf":{"@id":"http:\/\/www.orionpx.fr\/project\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/#primaryimage"},"image":{"@id":"https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/05\/ngc-6302.jpg","datePublished":"2015-05-26T11:47:00+00:00","description":"Il s'agit de la n\u00e9buleuse plan\u00e9taire du Papillon (ou NGC 6302). Visible dans la constellation du Scorpion. Une n\u00e9buleuse plan\u00e9taire n'a, en r\u00e9alit\u00e9, aucun rapport avec les plan\u00e8tes. C'est l'aspect circulaire de la plupart d\u2019entre-elles qui faisait penser aux plan\u00e8tes pour les astronomes du 18\u00e8me si\u00e8cle.","breadcrumb":{"@id":"https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/#primaryimage","url":"https:\/\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/05\/ngc-6302.jpg","contentUrl":"https:\/\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/05\/ngc-6302.jpg","width":3017,"height":3601},{"@type":"BreadcrumbList","@id":"https:\/\/www.orionpx.fr\/project\/blog\/la-nebuleuse-du-papillon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/www.orionpx.fr\/project\/blog\/"},{"@type":"ListItem","position":2,"name":"La n\u00e9buleuse du Papillon"}]},{"@type":"WebSite","@id":"http:\/\/www.orionpx.fr\/project\/blog\/#website","url":"http:\/\/www.orionpx.fr\/project\/blog\/","name":"Orion PX","description":"Blog de C.P. Rigel - Auteur de Science-Fiction","publisher":{"@id":"http:\/\/www.orionpx.fr\/project\/blog\/#\/schema\/person\/07536b10706cdf8a2a70fbd17f50de23"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.orionpx.fr\/project\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"http:\/\/www.orionpx.fr\/project\/blog\/#\/schema\/person\/07536b10706cdf8a2a70fbd17f50de23","name":"C.P. Rigel","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e4068dd5805dde1b4f1eca56e9247172d1266f72247697e59e0bd6ba6d631551?s=96&d=identicon&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e4068dd5805dde1b4f1eca56e9247172d1266f72247697e59e0bd6ba6d631551?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e4068dd5805dde1b4f1eca56e9247172d1266f72247697e59e0bd6ba6d631551?s=96&d=identicon&r=g","caption":"C.P. Rigel"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/e4068dd5805dde1b4f1eca56e9247172d1266f72247697e59e0bd6ba6d631551?s=96&d=identicon&r=g"},"description":"Je suis C.P. Rigel, analyste technique en informatique, je d\u00e9veloppe des logiciels pour une banque nord-am\u00e9ricaine. N\u00e9 en 1980, papa de deux formidables enfants, j\u2019ai la chance d\u2019avoir une vie de famille heureuse et bien remplie en France dans le d\u00e9partement de la Moselle. Curieux de tout, car pour moi tout est curieux. J\u2019ai ce besoin visc\u00e9ral d\u2019observer, d\u00e9cortiquer, d\u00e9monter, comprendre et apprendre. Tout est source de d\u00e9couverte et d\u2019\u00e9merveillement. Il \u00e9tait donc logique qu\u2019un jour je me tourne vers les myst\u00e8res de l\u2019univers. F\u00e9ru d\u2019astrophysique, de physique, et d\u2019astronomie, je n\u2019en suis pas moins un parfait amateur. J\u2019aime apprendre par moi-m\u00eame et d\u00e9battre de mes acquis pour les mettre \u00e0 l\u2019\u00e9preuve. (Le reste de ma biographie ici)","sameAs":["https:\/\/x.com\/Cprigel"],"url":"https:\/\/www.orionpx.fr\/project\/blog\/author\/cprigel\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/05\/ngc-6302.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4Oe1l-jR","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":809,"url":"https:\/\/www.orionpx.fr\/project\/blog\/les-etoiles-qui-sont-elles\/","url_meta":{"origin":1231,"position":0},"title":"Les \u00e9toiles: Qui sont-elles ?","author":"C.P. Rigel","date":"1 avril 2015","format":false,"excerpt":"Elles sont si nombreuse et si pr\u00e9sentes dans le ciel nocturne, qu'on en oublie parfois leur v\u00e9ritable nature. Les \u00e9toiles n'ont cess\u00e9 de fasciner nos anc\u00eatres, et furent le sujet de bien des l\u00e9gendes. Observ\u00e9 sans cesse, leurs mouvements particuliers sur la vo\u00fbte c\u00e9leste intrigua. Tous les peuples de la\u2026","rel":"","context":"Dans &quot;Espace &amp; Astrophysique&quot;","block_context":{"text":"Espace &amp; Astrophysique","link":"https:\/\/www.orionpx.fr\/project\/blog\/category\/divers\/espace\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/02\/sky2_1552774i.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/02\/sky2_1552774i.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/02\/sky2_1552774i.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1678,"url":"https:\/\/www.orionpx.fr\/project\/blog\/remanent-de-supernova-n63-a\/","url_meta":{"origin":1231,"position":1},"title":"R\u00e9manent de supernova N63 A","author":"C.P. Rigel","date":"19 octobre 2015","format":"image","excerpt":"Cette photographie, prise par le t\u00e9lescope spatial Hubble en 2008, montre une petite partie d'une pouponni\u00e8re\u00a0d'\u00e9toiles, appel\u00e9e N63, dans la galaxie naine du Grand Nuage de Magellan. Cette petite galaxie spirale est un satellite de la Voie Lact\u00e9e, distante du Soleil de 163 000 ann\u00e9es-lumi\u00e8re, elle est visible depuis\u00a0l'h\u00e9misph\u00e8re sud.\u2026","rel":"","context":"Dans &quot;La photo qui sort du lot&quot;","block_context":{"text":"La photo qui sort du lot","link":"https:\/\/www.orionpx.fr\/project\/blog\/category\/photos\/la-photo-qui-sort-du-lot\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/10\/N63A.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/10\/N63A.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/10\/N63A.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/10\/N63A.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/10\/N63A.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/10\/N63A.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":1781,"url":"https:\/\/www.orionpx.fr\/project\/blog\/mystic-mountain\/","url_meta":{"origin":1231,"position":2},"title":"Mystic Mountain","author":"C.P. Rigel","date":"24 d\u00e9cembre 2015","format":"image","excerpt":"Ce sapin de No\u00ebl monumental, constitu\u00e9 de gaz tels que l'hydrog\u00e8ne, est surnomm\u00e9 Mystic Mountain (la montagne mystique en fran\u00e7ais). Il s'agit d'un d\u00e9tail de la gigantesque n\u00e9buleuse de la Car\u00e8ne qui est visible depuis l'h\u00e9misph\u00e8re sud, dans la constellation de la Car\u00e8ne. Elle se trouve entre\u00a06500 et 10000 ann\u00e9es\u2026","rel":"","context":"Dans &quot;La photo qui sort du lot&quot;","block_context":{"text":"La photo qui sort du lot","link":"https:\/\/www.orionpx.fr\/project\/blog\/category\/photos\/la-photo-qui-sort-du-lot\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/12\/HH_901_and_HH_902_in_the_Carina_nebula_captured_by_the_Hubble_Space_Telescope.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/12\/HH_901_and_HH_902_in_the_Carina_nebula_captured_by_the_Hubble_Space_Telescope.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/12\/HH_901_and_HH_902_in_the_Carina_nebula_captured_by_the_Hubble_Space_Telescope.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/12\/HH_901_and_HH_902_in_the_Carina_nebula_captured_by_the_Hubble_Space_Telescope.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/12\/HH_901_and_HH_902_in_the_Carina_nebula_captured_by_the_Hubble_Space_Telescope.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/12\/HH_901_and_HH_902_in_the_Carina_nebula_captured_by_the_Hubble_Space_Telescope.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":830,"url":"https:\/\/www.orionpx.fr\/project\/blog\/les-piliers-de-la-creation\/","url_meta":{"origin":1231,"position":3},"title":"Les Piliers de la Cr\u00e9ation","author":"C.P. Rigel","date":"24 f\u00e9vrier 2015","format":"image","excerpt":"Cette incroyable photographie a \u00e9t\u00e9 prise par le t\u00e9lescope spatial Hubble en 2014 et publi\u00e9e par la NASA le 5 Janvier 2015. Il s'agit d'un clich\u00e9 en haute d\u00e9finition des Piliers de la Cr\u00e9ation, un d\u00e9tail de la n\u00e9buleuse de l'Aigle dans l'amas M16. Cette image unique \u00e0 \u00e9t\u00e9 s\u00e9lectionn\u00e9e\u2026","rel":"","context":"Dans &quot;La photo qui sort du lot&quot;","block_context":{"text":"La photo qui sort du lot","link":"https:\/\/www.orionpx.fr\/project\/blog\/category\/photos\/la-photo-qui-sort-du-lot\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/02\/m16-aigle-piliers-creation.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/02\/m16-aigle-piliers-creation.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/02\/m16-aigle-piliers-creation.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/02\/m16-aigle-piliers-creation.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/02\/m16-aigle-piliers-creation.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/02\/m16-aigle-piliers-creation.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":1629,"url":"https:\/\/www.orionpx.fr\/project\/blog\/les-cataclysmes-cosmiques\/","url_meta":{"origin":1231,"position":4},"title":"Les cataclysmes cosmiques","author":"C.P. Rigel","date":"15 octobre 2015","format":false,"excerpt":"Le 16 juillet 1945, au beau milieu du d\u00e9sert du Nouveau-Mexique, explosait la toute premi\u00e8re bombe \u00e0 fission nucl\u00e9aire. D\u00e9gageant une puissance de 21 kilotonnes, soit 87 864 Gigajoules. Ce jour l\u00e0, l'humanit\u00e9 eut un exemple concret de la quantit\u00e9 d'\u00e9nergie que pouvait contenir la mati\u00e8re. Et m\u00eame si ces\u2026","rel":"","context":"Dans &quot;Espace &amp; Astrophysique&quot;","block_context":{"text":"Espace &amp; Astrophysique","link":"https:\/\/www.orionpx.fr\/project\/blog\/category\/divers\/espace\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/10\/sun-outer-space-stars-explosions-planets-last-supernova-1440x1080-wallpaper.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/10\/sun-outer-space-stars-explosions-planets-last-supernova-1440x1080-wallpaper.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/10\/sun-outer-space-stars-explosions-planets-last-supernova-1440x1080-wallpaper.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/10\/sun-outer-space-stars-explosions-planets-last-supernova-1440x1080-wallpaper.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/10\/sun-outer-space-stars-explosions-planets-last-supernova-1440x1080-wallpaper.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2015\/10\/sun-outer-space-stars-explosions-planets-last-supernova-1440x1080-wallpaper.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":2362,"url":"https:\/\/www.orionpx.fr\/project\/blog\/astrophotographie-du-ciel-profond\/","url_meta":{"origin":1231,"position":5},"title":"Astrophotographie du ciel profond","author":"C.P. Rigel","date":"8 ao\u00fbt 2018","format":false,"excerpt":"J'ai mis \u00e0 jour la galerie de mes photos astro avec les derni\u00e8res que j'ai pu faire sur le ciel profond. Vous pouvez y acc\u00e9der par le menu ou en cliquant ici. J'alimenterai cette galerie\u00a0au fur et \u00e0 mesure de mes shoots, notez que je d\u00e9bute dans la photographie du\u2026","rel":"","context":"Dans &quot;Espace &amp; Astrophysique&quot;","block_context":{"text":"Espace &amp; Astrophysique","link":"https:\/\/www.orionpx.fr\/project\/blog\/category\/divers\/espace\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2018\/08\/4562179_3_b246_la-galaxie-m31-appelee-andromede_103c63f8d99291f6f6c2fb81de4bcd01.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2018\/08\/4562179_3_b246_la-galaxie-m31-appelee-andromede_103c63f8d99291f6f6c2fb81de4bcd01.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.orionpx.fr\/project\/blog\/wp-content\/uploads\/2018\/08\/4562179_3_b246_la-galaxie-m31-appelee-andromede_103c63f8d99291f6f6c2fb81de4bcd01.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.orionpx.fr\/project\/blog\/wp-json\/wp\/v2\/posts\/1231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.orionpx.fr\/project\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.orionpx.fr\/project\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.orionpx.fr\/project\/blog\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.orionpx.fr\/project\/blog\/wp-json\/wp\/v2\/comments?post=1231"}],"version-history":[{"count":4,"href":"https:\/\/www.orionpx.fr\/project\/blog\/wp-json\/wp\/v2\/posts\/1231\/revisions"}],"predecessor-version":[{"id":1235,"href":"https:\/\/www.orionpx.fr\/project\/blog\/wp-json\/wp\/v2\/posts\/1231\/revisions\/1235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.orionpx.fr\/project\/blog\/wp-json\/wp\/v2\/media\/1230"}],"wp:attachment":[{"href":"https:\/\/www.orionpx.fr\/project\/blog\/wp-json\/wp\/v2\/media?parent=1231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.orionpx.fr\/project\/blog\/wp-json\/wp\/v2\/categories?post=1231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.orionpx.fr\/project\/blog\/wp-json\/wp\/v2\/tags?post=1231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}